{"id":3208,"date":"2015-12-29T17:58:58","date_gmt":"2015-12-29T09:58:58","guid":{"rendered":"http:\/\/www.cemachinery.com\/es\/?p=3208"},"modified":"2018-03-21T11:35:16","modified_gmt":"2018-03-21T03:35:16","slug":"semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina","status":"publish","type":"post","link":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/","title":{"rendered":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina"},"content":{"rendered":"<p><span style=\"font-family: verdana,geneva;\"><a href=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg\"><img decoding=\"async\" class=\"size-full wp-image-1090\" src=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg\" alt=\"Semi-automatic-Coffee-Capsule-Sealing-Machine\" width=\"373\" height=\"366\" srcset=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg 373w, https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine-300x294.jpg 300w\" sizes=\"(max-width: 373px) 100vw, 373px\" \/><\/a><\/span><\/p>\n<p>El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula de caf\u00e9 sellado, Lavazza azul c\u00e1psula de caf\u00e9 sellado. Con la estructura compacta, el uso conveniente, f\u00e1cil mantenimiento y alta producci\u00f3n efficiency.Can funciona continuamente las 24 horas del d\u00eda. En materiales anticorrosivos, como el acero inoxidable, aleaciones de aluminio, cobre, etc.conforms a la ley de higiene de los alimentos, un rendimiento estable, es el equipo principal de una l\u00ednea de producci\u00f3n de alimentos confiable.<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 ez-toc-wrap-left counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a56d6e4a7064\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a56d6e4a7064\"  aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#Especificacion_de_la_Maquina_de_cafe_Capsula_Sellado\" >Especificaci\u00f3n de la M\u00e1quina de caf\u00e9 C\u00e1psula Sellado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#Caracteristica_de_la_maquina_de_cafe_de_la_capsula_Sellado\" >Caracter\u00edstica de la m\u00e1quina de caf\u00e9 de la c\u00e1psula Sellado<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#Video_de_Trabajo_del_Cafe_Capsula_sellado_de_la_maquina\" >V\u00eddeo de Trabajo del Caf\u00e9 C\u00e1psula sellado de la m\u00e1quina<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#Company_Profile\" >Company Profile<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#Send_Us_Inquiry_to_Get_Quotation\" >Send Us Inquiry to Get Quotation<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Especificacion_de_la_Maquina_de_cafe_Capsula_Sellado\"><\/span>Especificaci\u00f3n de la M\u00e1quina de caf\u00e9 C\u00e1psula Sellado<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Modelo: RMM<br \/>\nCapacidad: 300-700pcs \/ hora<br \/>\nTama\u00f1o de Sellado: De acuerdo a la muestra<br \/>\nVoltaje: 220V 50Hz (se puede personalizar)<br \/>\nPotencia: 250 w<br \/>\nConsumo de aire: no<br \/>\nPeso de la m\u00e1quina: 30 kg<br \/>\nTama\u00f1o de la m\u00e1quina: 300 * 250 * 550 mm<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1091\" src=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/K-Cup-Coffee-Capsule-Filling-Machine.jpg\" alt=\"K-Cup-Coffee-Capsule-Filling-Machine\" width=\"600\" height=\"401\" srcset=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/K-Cup-Coffee-Capsule-Filling-Machine.jpg 600w, https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/K-Cup-Coffee-Capsule-Filling-Machine-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Caracteristica_de_la_maquina_de_cafe_de_la_capsula_Sellado\"><\/span>Caracter\u00edstica de la m\u00e1quina de caf\u00e9 de la c\u00e1psula Sellado<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El bastidor de la m\u00e1quina es de acero \u00e1ngulo soldadas entre s\u00ed, despu\u00e9s del procesamiento antioxidante externalizaci\u00f3n 304 # acero inoxidable, las partes expuestas hacen procesamiento antioxidante y acero inoxidable, aluminio, etc, las partes materiales contactados para 304 # acero inoxidable y aluminio.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Video_de_Trabajo_del_Cafe_Capsula_sellado_de_la_maquina\"><\/span>V\u00eddeo de Trabajo del Caf\u00e9 C\u00e1psula sellado de la m\u00e1quina<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: verdana,geneva;\"><iframe src=\"\/\/www.youtube.com\/embed\/yMcMS1_mVTw\" width=\"560\" height=\"315\" frameborder=\"0\"><br \/>\n<\/iframe><\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Company_Profile\"><\/span><span style=\"font-family: verdana,geneva;\">Company Profile<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p><span style=\"font-family: verdana,geneva;\">Romiter Machinery Co., Ltd. is a market leading designer and a manufacturer of coffee capsule filling sealing machinery, include coffee capsule packing machine, coffee capsules filling sealing machine, nespresso capsules filling sealing machine, k-cup filling sealing machine, lavazza blue capsules filling sealing machine, coffee pod filling sealing machine, coffee pod packing machine.<\/span><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Send_Us_Inquiry_to_Get_Quotation\"><\/span><span style=\"background-color: #337fe5; color: #ffffff; font-family: verdana,geneva;\">Send Us Inquiry to Get Quotation<\/span><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<hr \/>\n<p><span style=\"font-family: verdana,geneva;\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f99-o1\" lang=\"zh-CN\" dir=\"ltr\" data-wpcf7-id=\"99\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/posts\/3208#wpcf7-f99-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"\u7559\u8a00\u8868\u5355\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"99\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"zh_CN\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f99-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<p>Please enter your contact information and the details you want to know about our product.\n<\/p>\n<p>Your Name (required)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p>Your Email (required)\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p>WhatsApp\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-whatsapp\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" id=\"your-whatsapp\" aria-invalid=\"false\" placeholder=\"Your WhatsApp ID with Country Code\" value=\"\" type=\"text\" name=\"your-whatsapp\" \/><\/span>\n<\/p>\n<p>Country\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-country\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Tell us Your Country\" value=\"\" type=\"text\" name=\"your-country\" \/><\/span>\n<\/p>\n<p>Subject\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n<\/p>\n<p>Your Message\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"please specify your detail requirement here\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"49\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula de caf\u00e9 sellado, Lavazza azul c\u00e1psula de caf\u00e9 sellado. Con la estructura compacta, el uso conveniente, f\u00e1cil mantenimiento y alta producci\u00f3n efficiency.Can funciona continuamente las 24 horas del d\u00eda. En materiales anticorrosivos, como el acero inoxidable, aleaciones de aluminio, cobre, etc.conforms a la ley de higiene de los alimentos, un rendimiento estable, es el equipo principal de una l\u00ednea de producci\u00f3n de alimentos confiable. Especificaci\u00f3n de la M\u00e1quina de caf\u00e9 C\u00e1psula Sellado Modelo: RMM Capacidad: 300-700pcs \/ hora Tama\u00f1o de Sellado: De acuerdo a la muestra Voltaje: 220V 50Hz (se puede personalizar) Potencia: 250 w Consumo de aire: no Peso de la m\u00e1quina: 30 kg &#8230;<\/p>\n","protected":false},"author":2,"featured_media":16185,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[807,815,817,819,1360],"tags":[891],"class_list":["post-3208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cafe-capsulas-embalaje-es","category-k-cup-capsula-sellado-llenado","category-lavazza-rellenar-de-la-capsula-sellado","category-nespresso-capsula-sellado-llenado","category-productos-populares","tag-semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Capsules Packing Machine\"\/>\n\t<meta name=\"google-site-verification\" content=\"_utraT85oyj6ciRBCsEmZZjBSrClIyZ7gHBptbju9zE\" \/>\n\t<meta name=\"keywords\" content=\"semi cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine\" \/>\n\t\t<meta property=\"og:description\" content=\"El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"373\" \/>\n\t\t<meta property=\"og:image:height\" content=\"366\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2015-12-29T09:58:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2018-03-21T03:35:16+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine\" \/>\n\t\t<meta name=\"twitter:description\" content=\"El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#article\",\"name\":\"Semi Cafetera autom\\u00e1tica de la c\\u00e1psula sellado de la m\\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine\",\"headline\":\"Semi Cafetera autom\\u00e1tica de la c\\u00e1psula sellado de la m\\u00e1quina\",\"author\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/author\\\/cemachinery\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.cemachinery.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg\",\"width\":373,\"height\":366,\"caption\":\"Semi-automatic-Coffee-Capsule-Sealing-Machine\"},\"datePublished\":\"2015-12-29T17:58:58+08:00\",\"dateModified\":\"2018-03-21T11:35:16+08:00\",\"inLanguage\":\"es-ES\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#webpage\"},\"articleSection\":\"Caf\\u00e9 C\\u00e1psulas Embalaje, K-Cup C\\u00e1psula Sellado Llenado, Lavazza rellenar de la c\\u00e1psula Sellado, Nespresso C\\u00e1psula Sellado Llenado, productos populares, Semi Cafetera autom\\u00e1tica de la c\\u00e1psula sellado de la m\\u00e1quina, Opcional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/#listItem\",\"name\":\"Producto\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/#listItem\",\"position\":2,\"name\":\"Producto\",\"item\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/cafe-capsulas-embalaje-es\\\/#listItem\",\"name\":\"Caf\\u00e9 C\\u00e1psulas Embalaje\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/cafe-capsulas-embalaje-es\\\/#listItem\",\"position\":3,\"name\":\"Caf\\u00e9 C\\u00e1psulas Embalaje\",\"item\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/cafe-capsulas-embalaje-es\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#listItem\",\"name\":\"Semi Cafetera autom\\u00e1tica de la c\\u00e1psula sellado de la m\\u00e1quina\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/#listItem\",\"name\":\"Producto\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#listItem\",\"position\":4,\"name\":\"Semi Cafetera autom\\u00e1tica de la c\\u00e1psula sellado de la m\\u00e1quina\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/producto\\\/cafe-capsulas-embalaje-es\\\/#listItem\",\"name\":\"Caf\\u00e9 C\\u00e1psulas Embalaje\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/#organization\",\"name\":\"Romiter Machinery\",\"description\":\"Romiter provides best coffee capsules filling sealing machine, including K-Cup, Nespresso coffee capsules filling and Sealing Machine, coffee pods filling and sealing machine, coffee capsules and coffee pods related machines\",\"url\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/\",\"telephone\":\"+8618637275223\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.cemachinery.com\\\/wp-content\\\/uploads\\\/2017\\\/09\\\/logo-Romiter.png\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#organizationLogo\",\"width\":268,\"height\":80,\"caption\":\"logo-Romiter\"},\"image\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/author\\\/cemachinery\\\/#author\",\"url\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/author\\\/cemachinery\\\/\",\"name\":\"Capsules Packing Machine\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a874ba945381a3139939bc6b95e4edfe0dc741de2fb81cfede615d36bb5035e6?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Capsules Packing Machine\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#webpage\",\"url\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/\",\"name\":\"Semi Cafetera autom\\u00e1tica de la c\\u00e1psula sellado de la m\\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine\",\"description\":\"El\\u00e9ctrico m\\u00e1quina de sellado de la c\\u00e1psula autom\\u00e1tica de caf\\u00e9 puede sellado autom\\u00e1tico, cortar la pel\\u00edcula. Relleno artificial, poner una caja, pel\\u00edcula autom\\u00e1tica (tambi\\u00e9n se puede poner la pel\\u00edcula manualmente) con sellado autom\\u00e1tico, corte autom\\u00e1tico. M\\u00e1quina de sellado de la c\\u00e1psula de caf\\u00e9 autom\\u00e1tica se puede utilizar para K-Cup c\\u00e1psula de caf\\u00e9 sellado, Nespresso c\\u00e1psula\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/author\\\/cemachinery\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/author\\\/cemachinery\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.cemachinery.com\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#mainImage\",\"width\":373,\"height\":366,\"caption\":\"Semi-automatic-Coffee-Capsule-Sealing-Machine\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\\\/#mainImage\"},\"datePublished\":\"2015-12-29T17:58:58+08:00\",\"dateModified\":\"2018-03-21T11:35:16+08:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/\",\"name\":\"Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine\",\"description\":\"Romiter provides best coffee capsules filling sealing machine, including K-Cup, Nespresso coffee capsules filling and Sealing Machine, coffee pods filling and sealing machine, coffee capsules and coffee pods related machines\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.cemachinery.com\\\/es\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine","description":"El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula","canonical_url":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/","robots":"max-image-preview:large","keywords":"semi cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina","webmasterTools":{"google-site-verification":"_utraT85oyj6ciRBCsEmZZjBSrClIyZ7gHBptbju9zE","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#article","name":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine","headline":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina","author":{"@id":"https:\/\/www.cemachinery.com\/es\/author\/cemachinery\/#author"},"publisher":{"@id":"https:\/\/www.cemachinery.com\/es\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg","width":373,"height":366,"caption":"Semi-automatic-Coffee-Capsule-Sealing-Machine"},"datePublished":"2015-12-29T17:58:58+08:00","dateModified":"2018-03-21T11:35:16+08:00","inLanguage":"es-ES","mainEntityOfPage":{"@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#webpage"},"isPartOf":{"@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#webpage"},"articleSection":"Caf\u00e9 C\u00e1psulas Embalaje, K-Cup C\u00e1psula Sellado Llenado, Lavazza rellenar de la c\u00e1psula Sellado, Nespresso C\u00e1psula Sellado Llenado, productos populares, Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina, Opcional"},{"@type":"BreadcrumbList","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/#listItem","position":1,"name":"Home","item":"https:\/\/www.cemachinery.com\/es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/producto\/#listItem","name":"Producto"}},{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/producto\/#listItem","position":2,"name":"Producto","item":"https:\/\/www.cemachinery.com\/es\/producto\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/producto\/cafe-capsulas-embalaje-es\/#listItem","name":"Caf\u00e9 C\u00e1psulas Embalaje"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/producto\/cafe-capsulas-embalaje-es\/#listItem","position":3,"name":"Caf\u00e9 C\u00e1psulas Embalaje","item":"https:\/\/www.cemachinery.com\/es\/producto\/cafe-capsulas-embalaje-es\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#listItem","name":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/producto\/#listItem","name":"Producto"}},{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#listItem","position":4,"name":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina","previousItem":{"@type":"ListItem","@id":"https:\/\/www.cemachinery.com\/es\/producto\/cafe-capsulas-embalaje-es\/#listItem","name":"Caf\u00e9 C\u00e1psulas Embalaje"}}]},{"@type":"Organization","@id":"https:\/\/www.cemachinery.com\/es\/#organization","name":"Romiter Machinery","description":"Romiter provides best coffee capsules filling sealing machine, including K-Cup, Nespresso coffee capsules filling and Sealing Machine, coffee pods filling and sealing machine, coffee capsules and coffee pods related machines","url":"https:\/\/www.cemachinery.com\/es\/","telephone":"+8618637275223","logo":{"@type":"ImageObject","url":"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2017\/09\/logo-Romiter.png","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#organizationLogo","width":268,"height":80,"caption":"logo-Romiter"},"image":{"@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/www.cemachinery.com\/es\/author\/cemachinery\/#author","url":"https:\/\/www.cemachinery.com\/es\/author\/cemachinery\/","name":"Capsules Packing Machine","image":{"@type":"ImageObject","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/a874ba945381a3139939bc6b95e4edfe0dc741de2fb81cfede615d36bb5035e6?s=96&d=mm&r=g","width":96,"height":96,"caption":"Capsules Packing Machine"}},{"@type":"WebPage","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#webpage","url":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/","name":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine","description":"El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/www.cemachinery.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#breadcrumblist"},"author":{"@id":"https:\/\/www.cemachinery.com\/es\/author\/cemachinery\/#author"},"creator":{"@id":"https:\/\/www.cemachinery.com\/es\/author\/cemachinery\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg","@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#mainImage","width":373,"height":366,"caption":"Semi-automatic-Coffee-Capsule-Sealing-Machine"},"primaryImageOfPage":{"@id":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/#mainImage"},"datePublished":"2015-12-29T17:58:58+08:00","dateModified":"2018-03-21T11:35:16+08:00"},{"@type":"WebSite","@id":"https:\/\/www.cemachinery.com\/es\/#website","url":"https:\/\/www.cemachinery.com\/es\/","name":"Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine","description":"Romiter provides best coffee capsules filling sealing machine, including K-Cup, Nespresso coffee capsules filling and Sealing Machine, coffee pods filling and sealing machine, coffee capsules and coffee pods related machines","inLanguage":"es-ES","publisher":{"@id":"https:\/\/www.cemachinery.com\/es\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine","og:type":"article","og:title":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine","og:description":"El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula","og:url":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/","og:image":"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg","og:image:secure_url":"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg","og:image:width":373,"og:image:height":366,"article:published_time":"2015-12-29T09:58:58+00:00","article:modified_time":"2018-03-21T03:35:16+00:00","twitter:card":"summary","twitter:title":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina | Nespresso Capsules Filling Sealing Machine, KCups Filling Sealing Machine, Coffee Capsules Filling Sealing Machine","twitter:description":"El\u00e9ctrico m\u00e1quina de sellado de la c\u00e1psula autom\u00e1tica de caf\u00e9 puede sellado autom\u00e1tico, cortar la pel\u00edcula. Relleno artificial, poner una caja, pel\u00edcula autom\u00e1tica (tambi\u00e9n se puede poner la pel\u00edcula manualmente) con sellado autom\u00e1tico, corte autom\u00e1tico. M\u00e1quina de sellado de la c\u00e1psula de caf\u00e9 autom\u00e1tica se puede utilizar para K-Cup c\u00e1psula de caf\u00e9 sellado, Nespresso c\u00e1psula","twitter:image":"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg"},"aioseo_meta_data":{"post_id":"3208","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"","defaultPostTypeGraph":""},"schema_type":null,"schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-03-06 09:46:13","updated":"2025-06-06 13:03:58","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.cemachinery.com\/es\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.cemachinery.com\/es\/producto\/\" title=\"Producto\">Producto<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.cemachinery.com\/es\/producto\/cafe-capsulas-embalaje-es\/\" title=\"Caf\u00e9 C\u00e1psulas Embalaje\">Caf\u00e9 C\u00e1psulas Embalaje<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tSemi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.cemachinery.com\/es\/"},{"label":"Producto","link":"https:\/\/www.cemachinery.com\/es\/producto\/"},{"label":"Caf\u00e9 C\u00e1psulas Embalaje","link":"https:\/\/www.cemachinery.com\/es\/producto\/cafe-capsulas-embalaje-es\/"},{"label":"Semi Cafetera autom\u00e1tica de la c\u00e1psula sellado de la m\u00e1quina","link":"https:\/\/www.cemachinery.com\/es\/semi-cafetera-automatica-de-la-capsula-sellado-de-la-maquina\/"}],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.cemachinery.com\/wp-content\/uploads\/2014\/10\/Semi-automatic-Coffee-Capsule-Sealing-Machine.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/posts\/3208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/comments?post=3208"}],"version-history":[{"count":0,"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/posts\/3208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/media\/16185"}],"wp:attachment":[{"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/media?parent=3208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/categories?post=3208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cemachinery.com\/es\/wp-json\/wp\/v2\/tags?post=3208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}